{"id":10051,"date":"2014-08-20T20:01:37","date_gmt":"2014-08-20T17:01:37","guid":{"rendered":"http:\/\/www.sursamedicala.ro\/blog\/\/marcaj-genetic\/"},"modified":"2014-08-20T20:01:37","modified_gmt":"2014-08-20T17:01:37","slug":"marcaj-genetic","status":"publish","type":"post","link":"https:\/\/www.sursamedicala.ro\/blog\/marcaj-genetic\/","title":{"rendered":"MARCAJ GENETIC"},"content":{"rendered":"<p>MARCAJ GENETIC \/ etiquetage genetique \/ gene tagging. Insertia unui &#8216;marker genetic In interiorul sau In apropierea unei gene. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>MARCAJ GENETIC \/ etiquetage genetique \/ gene tagging. Insertia unui &#8216;marker genetic In interiorul sau In apropierea unei gene.<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[3],"tags":[],"class_list":{"0":"post-10051","1":"post","2":"type-post","3":"status-publish","4":"format-standard","6":"category-dictionar-medical"},"_links":{"self":[{"href":"https:\/\/www.sursamedicala.ro\/blog\/wp-json\/wp\/v2\/posts\/10051","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sursamedicala.ro\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sursamedicala.ro\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sursamedicala.ro\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sursamedicala.ro\/blog\/wp-json\/wp\/v2\/comments?post=10051"}],"version-history":[{"count":0,"href":"https:\/\/www.sursamedicala.ro\/blog\/wp-json\/wp\/v2\/posts\/10051\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.sursamedicala.ro\/blog\/wp-json\/wp\/v2\/media?parent=10051"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sursamedicala.ro\/blog\/wp-json\/wp\/v2\/categories?post=10051"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sursamedicala.ro\/blog\/wp-json\/wp\/v2\/tags?post=10051"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}